{"id":98561,"date":"2024-09-13T07:44:06","date_gmt":"2024-09-13T07:44:06","guid":{"rendered":"https:\/\/moto-oprema.com\/Artikel\/alpinestars-lederjacke-faster-v3-schwarz-weiss\/"},"modified":"2024-09-13T07:44:06","modified_gmt":"2024-09-13T07:44:06","slug":"alpinestars-lederjacke-faster-v3-schwarz-weiss","status":"publish","type":"product","link":"https:\/\/moto-oprema.com\/de\/Artikel\/alpinestars-lederjacke-faster-v3-schwarz-weiss\/","title":{"rendered":"ALPINESTARS LEDERJACKE FASTER V3 SCHWARZ WEISS"},"content":{"rendered":"<p>Die Faster v3 Lederjacke ist eine erstklassig gestaltete Sportmotorradjacke mit hochwertigem Leder und umfangreichen HRSF-Stretcheins\u00e4tzen f\u00fcr optimale Abriebfestigkeit und verbesserte Beweglichkeit. Sie kombiniert hervorragende Schutzeigenschaften mit \u00fcberragendem Fahrerkomfort. Die raffinierte, verbesserte Sportsilhouette der Jacke nutzt dynamische Linien und Verarbeitungsdetails, um einen frischen und modernen, vom Rennsport abgeleiteten Stil zu bieten.  <\/p>\n<ul>\n<li>\u00c4u\u00dferst strapazierf\u00e4higes und technisches Leder mit mehrschichtiger Konstruktion f\u00fcr Widerstandsf\u00e4higkeit und Komfort<\/li>\n<li>Gro\u00dfe, fortschrittliche HRSF-Stretcheins\u00e4tze an Brust, R\u00fccken, Bauch, Achseln, Schulterbl\u00e4ttern und Innenarmen f\u00fcr eine optimale, leistungsstarke Passform und maximale Bewegungsfreiheit auf dem Rad.<\/li>\n<li>Sportliche Passform mit vorgeformten Schultern und ergonomischen Ellbogen f\u00fcr \u00fcberragenden Komfort und Sitz.<\/li>\n<li>Bel\u00fcftungs\u00f6ffnungen mit Rei\u00dfverschluss an den Seiten des Oberk\u00f6rpers f\u00fcr zus\u00e4tzliche Ventilation.<\/li>\n<li>Verstellen Sie den Bund f\u00fcr eine individuelle Passform.<\/li>\n<li>Neue, ergonomische, ausgeschnittene Kragenkonstruktion mit einem Innenkragen aus synthetischem Wildleder f\u00fcr verbesserten Reiterkomfort.<\/li>\n<\/ul>\n<p>80% Leder 20% Polyester<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Faster v3 Lederjacke ist eine erstklassig gestaltete Sportmotorradjacke mit hochwertigem Leder und umfangreichen HRSF-Stretcheins\u00e4tzen f\u00fcr&#8230;<\/p>\n","protected":false},"featured_media":30513,"comment_status":"open","ping_status":"open","template":"","meta":{"_acf_changed":false},"brand":[2111],"gender":[],"product_brand":[],"product_cat":[1357,2045,2048],"product_tag":[],"class_list":{"0":"post-98561","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"brand-alpinestars-de","7":"product_cat-ausrustung-fur-motorradfahrer","8":"product_cat-jakne-de","9":"product_cat-textil-jacken","10":"pa_velikost-st-46-de","11":"pa_velikost-st-48-de","12":"pa_velikost-st-50-de","13":"pa_velikost-st-52-de","14":"pa_velikost-st-54-de","15":"pa_velikost-st-56-de","16":"pa_velikost-st-58-de","17":"pa_velikost-st-60-de","19":"first","20":"onbackorder","21":"sale","22":"taxable","23":"shipping-taxable","24":"purchasable","25":"product-type-variable"},"acf":[],"_links":{"self":[{"href":"https:\/\/moto-oprema.com\/de\/wp-json\/wp\/v2\/product\/98561","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/moto-oprema.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/moto-oprema.com\/de\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/moto-oprema.com\/de\/wp-json\/wp\/v2\/comments?post=98561"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/moto-oprema.com\/de\/wp-json\/wp\/v2\/media\/30513"}],"wp:attachment":[{"href":"https:\/\/moto-oprema.com\/de\/wp-json\/wp\/v2\/media?parent=98561"}],"wp:term":[{"taxonomy":"brand","embeddable":true,"href":"https:\/\/moto-oprema.com\/de\/wp-json\/wp\/v2\/brand?post=98561"},{"taxonomy":"gender","embeddable":true,"href":"https:\/\/moto-oprema.com\/de\/wp-json\/wp\/v2\/gender?post=98561"},{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/moto-oprema.com\/de\/wp-json\/wp\/v2\/product_brand?post=98561"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/moto-oprema.com\/de\/wp-json\/wp\/v2\/product_cat?post=98561"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/moto-oprema.com\/de\/wp-json\/wp\/v2\/product_tag?post=98561"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}