{"id":93602,"date":"2025-05-21T09:18:34","date_gmt":"2025-05-21T09:18:34","guid":{"rendered":"https:\/\/moto-oprema.com\/Artikel\/xpd-x-journey-h2out-stiefel-schwarz\/"},"modified":"2025-05-21T09:18:34","modified_gmt":"2025-05-21T09:18:34","slug":"xpd-x-journey-h2out-stiefel-schwarz","status":"publish","type":"product","link":"https:\/\/moto-oprema.com\/de\/Artikel\/xpd-x-journey-h2out-stiefel-schwarz\/","title":{"rendered":"XPD X-JOURNEY H2OUT STIEFEL SCHWARZ"},"content":{"rendered":"<p>Mit den X-JOURNEY H2OUT\u00ae Wanderschuhen erhalten Sie ein Accessoire f\u00fcr jedes Abenteuer. Das \u00e4u\u00dferst abriebfeste und wasserabweisende Obermaterial aus hochfestem Gewebe sorgt f\u00fcr ein sorgenfreies Unterwegssein, sowohl was die Sicherheit als auch das Wetter betrifft. F\u00fcr Komfort sorgen die Memory-Foam-Polsterung, die sich an die Form Ihres Fu\u00dfes anpasst, ein gepolsterter Kragen und eine geformte und ergonomisch geformte Einlegesohle aus Nylon.  <\/p>\n<p>Extern:<\/p>\n<p>Obermaterial: wasserabweisend behandelte Mikrofaser mit hoher Abriebfestigkeit und sehr strapazierf\u00e4higem Textilmaterial.<br \/>\nGriffige, vulkanisierte Gummisohle.<br \/>\nSchutz durch Werkzeugfutter.<br \/>\nGepolsterter Kragen f\u00fcr mehr Komfort.<br \/>\nRei\u00dfverschluss und Klettverschluss.<br \/>\nThermisch geschwei\u00dfte und personalisierte Frontplatte.<br \/>\nReflektierende Einlegesohle hinten.<\/p>\n<p>Innen:<\/p>\n<p>Wasserdichte und atmungsaktive H2OUT\u00ae Schlauchmembran.<br \/>\n3D Air Mesh-Kragen f\u00fcr erh\u00f6hte Atmungsaktivit\u00e4t.<br \/>\nSchienbein- und Kn\u00f6chelschutz aus geformtem TPU-Kunststoff.<br \/>\nVerst\u00e4rkter Zehen- und Fersenbereich.<br \/>\nWeiche Polymer-Polsterung mit Memory Foam.<br \/>\nMittlere D.F.A. (Differentiated Flexibility Area) geformte und ergonomische langlebige Nylon-Einlegesohle.<br \/>\nAir Tech Sensitive Fit und antibakterielles Wechselfu\u00dfbett.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mit den X-JOURNEY H2OUT\u00ae Wanderschuhen erhalten Sie ein Accessoire f\u00fcr jedes Abenteuer. Das \u00e4u\u00dferst abriebfeste und&#8230;<\/p>\n","protected":false},"featured_media":89097,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"brand":[2162],"gender":[],"product_brand":[],"product_cat":[1357,2043,2049],"product_tag":[],"class_list":{"0":"post-93602","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"brand-xpd-de","7":"product_cat-ausrustung-fur-motorradfahrer","8":"product_cat-schuhe","9":"product_cat-touring-schuhe","10":"pa_velikost-skornji-36-de","11":"pa_velikost-skornji-37-de","12":"pa_velikost-skornji-38-de","13":"pa_velikost-skornji-39-de","14":"pa_velikost-skornji-40-de","15":"pa_velikost-skornji-41-de","16":"pa_velikost-skornji-42-de","17":"pa_velikost-skornji-43-de","18":"pa_velikost-skornji-44-de","19":"pa_velikost-skornji-45-de","20":"pa_velikost-skornji-46-de","21":"pa_velikost-skornji-47-de","22":"pa_velikost-skornji-48-de","24":"first","25":"instock","26":"sale","27":"taxable","28":"shipping-taxable","29":"purchasable","30":"product-type-variable"},"acf":[],"_links":{"self":[{"href":"https:\/\/moto-oprema.com\/de\/wp-json\/wp\/v2\/product\/93602","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/moto-oprema.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/moto-oprema.com\/de\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/moto-oprema.com\/de\/wp-json\/wp\/v2\/comments?post=93602"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/moto-oprema.com\/de\/wp-json\/wp\/v2\/media\/89097"}],"wp:attachment":[{"href":"https:\/\/moto-oprema.com\/de\/wp-json\/wp\/v2\/media?parent=93602"}],"wp:term":[{"taxonomy":"brand","embeddable":true,"href":"https:\/\/moto-oprema.com\/de\/wp-json\/wp\/v2\/brand?post=93602"},{"taxonomy":"gender","embeddable":true,"href":"https:\/\/moto-oprema.com\/de\/wp-json\/wp\/v2\/gender?post=93602"},{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/moto-oprema.com\/de\/wp-json\/wp\/v2\/product_brand?post=93602"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/moto-oprema.com\/de\/wp-json\/wp\/v2\/product_cat?post=93602"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/moto-oprema.com\/de\/wp-json\/wp\/v2\/product_tag?post=93602"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}